{"id":1657,"date":"2011-08-01T17:05:03","date_gmt":"2011-08-01T15:05:03","guid":{"rendered":"http:\/\/www.mega-stoffel.de\/weblog\/?p=1657"},"modified":"2011-08-01T17:05:03","modified_gmt":"2011-08-01T15:05:03","slug":"geldbeutel","status":"publish","type":"post","link":"https:\/\/mega-stoffel.de\/weblog\/2011\/08\/01\/geldbeutel\/","title":{"rendered":"Geldbeutel"},"content":{"rendered":"<p>bevor ich mir jetzt einen abbreche und etwas vom neuen Portmon\u00e4h schreibe, sage ich lieber, dass ich einen neuen Geldbeutel habe.<br \/>\nVermutlich kennt Ihr das alle, dass man fast keinen richtigen Geldbeutel mehr finden kann. \u00dcberall sieht man nur so riesige Teile, in die man neben Geld und ein paar Kleinigkeiten noch mindestens 25 Karten und 18 Fotos einstecken kann. Wer braucht sowas jeden Tag?<br \/>\nIch auf jeden Fall nicht. Ich will nur etwas Geld, meinen Personalausweis und meine Jahrekarte f\u00fcr die U-Bahn t\u00e4glich dabei haben. Alles andere nur bei Bedarf.<br \/>\nUnd ich habe jetzt doch tats\u00e4chlich in Stuttgart mal so einen Geldbeutel <a title=\"vern\u00fcnftige Geldbeutel und viel mehr!\" href=\"http:\/\/www.die-lederschmiede.de\/\" target=\"_blank\">gefunden<\/a>:<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1658\" title=\"Leder-Geldbeutel in passender Personalausweis-Gr\u00f6\u00dfe\" src=\"http:\/\/www.mega-stoffel.de\/weblog\/wp-content\/uploads\/2011\/09\/110801.jpg\" alt=\"\" width=\"600\" height=\"399\" \/><br \/>\nSomit kann ich mein bestimmt schon 15 Jahre altes Teil endlich mal wegschmei\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>bevor ich mir jetzt einen abbreche und etwas vom neuen Portmon\u00e4h schreibe, sage ich lieber, dass ich einen neuen Geldbeutel habe. Vermutlich kennt Ihr das alle, dass man fast keinen richtigen Geldbeutel mehr finden kann. \u00dcberall sieht man nur so riesige Teile, in die man neben Geld und ein paar Kleinigkeiten noch mindestens 25 Karten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[5,11],"tags":[],"class_list":["post-1657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gedanken","category-veranderungen"],"_links":{"self":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/posts\/1657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/comments?post=1657"}],"version-history":[{"count":0,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/posts\/1657\/revisions"}],"wp:attachment":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/media?parent=1657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/categories?post=1657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/tags?post=1657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}