{"id":4103,"date":"2015-03-30T20:05:02","date_gmt":"2015-03-30T18:05:02","guid":{"rendered":"http:\/\/www.mega-stoffel.de\/weblog\/?p=4103"},"modified":"2015-03-30T20:05:02","modified_gmt":"2015-03-30T18:05:02","slug":"trainingslager-2","status":"publish","type":"post","link":"https:\/\/mega-stoffel.de\/weblog\/2015\/03\/30\/trainingslager-2\/","title":{"rendered":"Trainingslager \/2"},"content":{"rendered":"<p>nachdem mir gestern gezeigt wurde, dass es tats\u00e4chlich Leute gibt, die noch schneller als ich Rennrad fahren (und ich nicht mal\u00a0mit der Carbon-Ausr\u00fcstung punkten konnte), habe ich mich heute f\u00fcr die langsamerere Gruppe im Schnitt von 22-24km\/h eingereiht. Das ist mir zwar zu langsam, es macht aber viel mehr Spa\u00df, vorne weg zu fahren, als immer nur hinterher zu strampeln. Und nach den ca. 100km von gestern wollte ich bei den heutigen 120km bei 1800 H\u00f6henmetern lieber nicht \u00fcberfordert werden. Dazu kommt auch, dass mich das Hotel mit seinem B\u00fcffet nicht unbedingt vom Hocker haut.<br \/>\nNach der Tour ging es zuerst mal wieder in ein Cafe um ein &#8222;Champu&#8220; zu trinken, das ist deren Radler hier, nur eben nicht mit Zitronen- sondern Orangenlimonade. Auch gut.<br \/>\nUnd dann geht&#8217;s in den\/das Spa nebenan. Trotz deutlich mehr Haaren im Gesicht als auf dem Kopf ist das Tragen einer Badem\u00fctze dort &#8222;obligatorisch&#8220;. Wenn ich das gewusst h\u00e4tte, h\u00e4tte ich meine Hippie-Batik-Badekappe mitgebracht. Jetzt ist es halt eine normale Schwarze f\u00fcr 2\u20ac.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4104\" src=\"http:\/\/www.mega-stoffel.de\/weblog\/wp-content\/uploads\/2015\/05\/Badekappe.jpg\" alt=\"Bart und Badekappe\" width=\"900\" height=\"448\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>nachdem mir gestern gezeigt wurde, dass es tats\u00e4chlich Leute gibt, die noch schneller als ich Rennrad fahren (und ich nicht mal\u00a0mit der Carbon-Ausr\u00fcstung punkten konnte), habe ich mich heute f\u00fcr die langsamerere Gruppe im Schnitt von 22-24km\/h eingereiht. Das ist mir zwar zu langsam, es macht aber viel mehr Spa\u00df, vorne weg zu fahren, als [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[4,38,5,16],"tags":[],"class_list":["post-4103","post","type-post","status-publish","format-standard","hentry","category-n-bild","category-cambrils","category-gedanken","category-sport"],"_links":{"self":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/posts\/4103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/comments?post=4103"}],"version-history":[{"count":0,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/posts\/4103\/revisions"}],"wp:attachment":[{"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/media?parent=4103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/categories?post=4103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mega-stoffel.de\/weblog\/wp-json\/wp\/v2\/tags?post=4103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}